{"id":8501,"date":"2020-12-02T11:28:31","date_gmt":"2020-12-02T11:28:31","guid":{"rendered":"https:\/\/aalberts-st.flywheelsites.com\/location\/laupheim\/"},"modified":"2026-05-06T15:57:55","modified_gmt":"2026-05-06T13:57:55","slug":"laupheim","status":"publish","type":"location","link":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/","title":{"rendered":"Aalberts surface technologies Laupheim"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8501\" class=\"elementor elementor-8501 elementor-988\" data-elementor-post-type=\"location\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8b747e elementor-section-height-min-height page-header elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d8b747e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71a70dd5\" data-id=\"71a70dd5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b52846d elementor-widget elementor-widget-text-editor\" data-id=\"4b52846d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>heat treatment<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-399c3620 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"399c3620\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aalberts surface technologies Laupheim<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8fe11 white_bc elementor-widget elementor-widget-wp-widget-bcn_widget\" data-id=\"0e8fe11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wp-widget-bcn_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"breadcrumbs\" vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\"><span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Go to Aalberts surface technologies.\" href=\"https:\/\/www.aalberts-st.com\/de\/\" class=\"home\" ><span property=\"name\">Aalberts surface technologies<\/span><\/a><meta property=\"position\" content=\"1\"><\/span> &gt; <span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Go to \u00dcber uns.\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/\" class=\"post post-page\" ><span property=\"name\">\u00dcber uns<\/span><\/a><meta property=\"position\" content=\"2\"><\/span> &gt; <span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Go to News.\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/\" class=\"post-root post post-post\" aria-current=\"page\"><span property=\"name\">News<\/span><\/a><meta property=\"position\" content=\"3\"><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1246dac5 anchor_link elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1246dac5\" data-element_type=\"section\" data-e-type=\"section\" id=\"ueber\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1c5cb82d\" data-id=\"1c5cb82d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-117ed40d parent-sticky elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"117ed40d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-55f8171 sticky\" data-id=\"55f8171\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43d3e16b read-more cstm_anchor elementor-widget elementor-widget-button\" data-id=\"43d3e16b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#ueber\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00dcber den Standort<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c769b3e read-more cstm_anchor elementor-widget elementor-widget-button\" data-id=\"4c769b3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#downloads\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Downloads<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76381ae7 read-more cstm_anchor elementor-widget elementor-widget-button\" data-id=\"76381ae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#verfahren\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Unsere Verfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d1b792 read-more cstm_anchor elementor-widget elementor-widget-button\" data-id=\"17d1b792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#branchen\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Branchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b515b2 elementor-widget elementor-widget-button\" data-id=\"77b515b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#Kontakt\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-78c50284\" data-id=\"78c50284\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71a4105a elementor-widget elementor-widget-heading\" data-id=\"71a4105a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber unseren Standort in Laupheim<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0025584 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0025584\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-27847ff\" data-id=\"27847ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-252cc64c elementor-widget elementor-widget-text-editor\" data-id=\"252cc64c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Standort, der aus der fr\u00fcheren H\u00e4rterei des damaligen Drehteilherstellers Lindenmaier hervorging, kann auf eine rund 70-j\u00e4hrige Erfolgsgeschichte zur\u00fcckblicken.<\/p><p>Es verf\u00fcgt \u00fcber <strong>hochmoderne Verfahrens- und Anagentechnologien<\/strong>, insbesondere in der H\u00e4rterei.<\/p><p>Je nach Verfahren, Teilespektrum und Teilebed\u00fcrfnis sorgt der Sondergestellbau f\u00fcr noch effektivere &amp; wirtschaftlichere Prozesse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c508af6\" data-id=\"c508af6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b51045e elementor-widget elementor-widget-image\" data-id=\"b51045e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1210\" height=\"908\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg\" class=\"attachment-full size-full wp-image-33894\" alt=\"Aalberts Surface Technologies Laupheim\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg.webp 1210w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim-267x200.jpg.webp 267w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim-1024x768.jpg.webp 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim-768x576.jpg.webp 768w\" sizes=\"(max-width: 1210px) 100vw, 1210px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d59ed6 elementor-widget elementor-widget-text-editor\" data-id=\"3d59ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Die Zufriedenheit und der Erfolg unserer Kunden sind unsere obersten Ziele.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-25fea39 elementor-widget elementor-widget-text-editor\" data-id=\"25fea39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Immer h\u00f6her werdende Sauberkeitsanforderungen an die Bauteile werden mittels <strong>modernster Reinigungstechnologie<\/strong> erf\u00fcllt. Das Spezialistenteam in Laupheim fungiert f\u00fcr viele seiner Kunden als Systemlieferant.<\/p><p>Nutzen Sie die Leistungsst\u00e4rke eines der f\u00fchrenden und erfahrenen Unternehmen Europas auf dem Sektor der W\u00e4rmebehandlung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d164ab6 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"d164ab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-6619752 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Kammerofen Laupheim\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-eb4534b swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Retortenofen Laupheim\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div><div class=\"elementor-repeater-item-5d4dd3a swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"Anlage Laupheim\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Vorheriger Slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster Slide\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d8de2 elementor-widget elementor-widget-heading\" data-id=\"d9d8de2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leistungs\u00fcbersicht der W\u00e4rmebehandlungen in Laupheim<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00c84f7 process-detail elementor-widget elementor-widget-accordion\" data-id=\"00c84f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8201\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8201\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Thermische Verfahren<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8201\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8201\"><p>H\u00e4rten in Kammer\u00f6fen<\/p><p>Gl\u00fchen in Kammer\u00f6fen<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8202\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8202\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Thermochemische Verfahren<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8202\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8202\"><p>Aufkohlen &amp; Einsatzh\u00e4rten in Kammer\u00f6fen<\/p><p>Carbonitrieren in Kammer\u00f6fen<\/p><p>Nitrieren &amp; Nitrocarburieren in Retorten\u00f6fen<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90beb80 process-detail elementor-widget elementor-widget-accordion\" data-id=\"90beb80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1511\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1511\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Sonderleistungen<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1511\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1511\"><p>Waschmaschinen (L\u00f6sungsmittel und w\u00e4ssrig)<\/p><p>Tiefk\u00fchltruhen<\/p><p>Strahlanlagen<\/p><p>H\u00e4rtepr\u00fcfung HB, HV, HRC<\/p><p>Metallografische Untersuchung<\/p><p>Schichtdickenmessung<\/p><p>Risspr\u00fcfung<\/p><p>Hol- und Bringdienst<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a9f94 elementor-widget elementor-widget-heading\" data-id=\"d2a9f94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00f6chste Qualit\u00e4t: Pr\u00e4zise W\u00e4rmebehandlung in Laupheim<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab4056 elementor-widget elementor-widget-text-editor\" data-id=\"6ab4056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Anspruch ist h\u00f6chste Qualit\u00e4t. Dies gilt sowohl f\u00fcr die Bearbeitung Ihrer Produkte als auch f\u00fcr den Umgang mit unseren Kunden und dem sich daraus resultierenden ganzheitlichen Service, den wir Ihnen bieten.<\/p><p>In Laupheim ist der Standort f\u00fcr seine ISO- und IATF-zertifizierten Verfahren in der W\u00e4rmebehandlung bekannt. Wir stehen f\u00fcr einen <strong>optimalen, reproduzierbaren Qualit\u00e4tsstandard<\/strong> ein, den wir gleicherma\u00dfen f\u00fcr Serienteile wie f\u00fcr einzelne Maschinenkomponenten als Ma\u00dfstab ansetzen. Dabei verstehen wir <strong>Qualit\u00e4t als ein Teil Ihrer Zufriedenheit<\/strong>, die selbstverst\u00e4ndlich auch Termintreue, Pr\u00e4zision und Zuverl\u00e4ssigkeit miteinschlie\u00dft. Unsere Dienstleistungen in der W\u00e4rmebehandlung garantieren Ihnen genau diese Standards. Die Dienstleistungsmentalit\u00e4t ist unser Anspruch alles zu tun, um unsere Kunden zufriedener und erfolgreicher zu machen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d917b6 elementor-widget elementor-widget-gallery\" data-id=\"8d917b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:2,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/02\/DSC_1337-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d917b6\" data-elementor-lightbox-title=\"w\u00e4rmebehandlung laupheim\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjI0MTAsInVybCI6Imh0dHBzOlwvXC93d3cuYWFsYmVydHMtc3QuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIxXC8wMlwvRFNDXzEzMzctc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjhkOTE3YjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/02\/DSC_1337-300x200.jpg\" data-width=\"300\" data-height=\"200\" aria-label=\"w\u00e4rmebehandlung laupheim\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/02\/DSC_1192-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"8d917b6\" data-elementor-lightbox-title=\"DSC_1192\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjIzOTIsInVybCI6Imh0dHBzOlwvXC93d3cuYWFsYmVydHMtc3QuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIxXC8wMlwvRFNDXzExOTItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjhkOTE3YjYifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/02\/DSC_1192-300x200.jpg\" data-width=\"300\" data-height=\"200\" aria-label=\"h\u00e4rten laupheim\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65b0b6e elementor-widget elementor-widget-text-editor\" data-id=\"65b0b6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei uns behandelte Bauteile finden Anwendung in einem breiten Einsatzbereich. Unsere Qualit\u00e4t zeigt sich bei vielen Komponenten der Automobilindustrie im Antriebsstrang bis hin zu kritischen Sicherheitsbauteilen. Gleicherma\u00dfen zeigt sich unsere Zuverl\u00e4ssigkeit im Kranbau und im Maschinenbau, bei Windkraftanlagen und Werkzeugmaschinen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ef9b4fa anchor_link elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ef9b4fa\" data-element_type=\"section\" data-e-type=\"section\" id=\"downloads\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3631a48d\" data-id=\"3631a48d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-55d5e293\" data-id=\"55d5e293\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b5fdced elementor-widget elementor-widget-heading\" data-id=\"7b5fdced\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Downloads<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dc2ff35 elementor-widget elementor-widget-text-editor\" data-id=\"1dc2ff35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Standort in Laupheim ist mit seiner W\u00e4rmebehandlungstechnologie <strong>ISO- und IATF-zertifiziert.<\/strong> Wir stehen f\u00fcr einen <strong>optimalen, reproduzierbaren Qualit\u00e4tsstandard<\/strong> ein, den wir gleicherma\u00dfen f\u00fcr Serienteile wie f\u00fcr einzelne Maschinenkomponenten als Ma\u00dfstab ansetzen.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21771e9e elementor-widget elementor-widget-heading\" data-id=\"21771e9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Zertifikate<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2149091c elementor-widget elementor-widget-shortcode\" data-id=\"2149091c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"container-bestand certi\"><div class=\"file\"><a target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2024\/10\/iatf-16949-Laupheim-2024-de.pdf\"> <span class=\"part title_pdf\">IATF 16949:2016<\/span>\n                    <\/a>\n                    <\/div>\n                                <div class=\"file\"><a target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/05\/iso-50001-remscheid-laupheim-gaildorf-werther-kehl-dunningen-de-2026.pdf\"> <span class=\"part title_pdf\">ISO 50001:2018<\/span>\n                    <\/a>\n                    <\/div>\n                                <div class=\"file\"><a target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2024\/03\/iso-14001-remscheid-2024-de.pdf\"> <span class=\"part title_pdf\">ISO 14001:2015<\/span>\n                    <\/a>\n                    <\/div>\n                                <\/div>\t\t<div class=\"elementor-shortcode\"> <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e11b10c elementor-widget elementor-widget-heading\" data-id=\"4e11b10c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">AGBs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d47da8 elementor-widget elementor-widget-shortcode\" data-id=\"2d47da8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"container-bestand certi\">\n                                        <div class=\"file\">\n                            <a target=\"_blank\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/07\/Gaildorf-Kronberg-Kehl-Laupheim_DE_Einkaufsbedingungen-2025.pdf\">\n                                 <span class=\"part title_pdf\">Einkaufsbedingungen (Gaildorf, Kehl, Laupheim)<\/span>                             <\/a>\n                        <\/div>\n                                            <div class=\"file\">\n                            <a target=\"_blank\" href=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/07\/Gaildorf-Kronberg-Kehl-Laupheim_DE_Liefer-u-Leistungsbedingungen-2025.pdf\">\n                                 <span class=\"part title_pdf\">Liefer- und Leistungsbedingungen (Gaildorf, Kehl, Laupheim)<\/span>                             <\/a>\n                        <\/div>\n                                <\/div>\n        \t\t<div class=\"elementor-shortcode\"> <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23653511 anchor_link elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23653511\" data-element_type=\"section\" data-e-type=\"section\" id=\"verfahren\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4cdafc49\" data-id=\"4cdafc49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-a207bea\" data-id=\"a207bea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-387f905d elementor-widget elementor-widget-heading\" data-id=\"387f905d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Verfahren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dd14b85 elementor-widget elementor-widget-text-editor\" data-id=\"1dd14b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Als <strong>Spezialisten f\u00fcr W\u00e4rmebehandlung<\/strong>, insbesondere in der H\u00e4rterei, bieten wir Ihnen im baden-w\u00fcrttembergischen Laupheim Best-in-Class L\u00f6sungen f\u00fcr Ihre Anforderungen in bestm\u00f6glicher Qualit\u00e4t. Ihre Zufriedenheit ist f\u00fcr uns oberstes Ziel. Dabei bieten wir Ihnen unseren <strong>ganzheitlichen Service<\/strong> von der Abholung der Bauteile bei Ihnen bis hin zur Just-in-Time-Auslieferung zu Ihrem Wunschziel als zertifiziertes Unternehmen an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142b541 elementor-widget elementor-widget-shortcode\" data-id=\"142b541\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">        <div class=\"container process location\">\n                                                                                <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/atmosphaerisches-aufkohlen\/\">\n                        <!--  -->\n                        Atmosph\u00e4risches Aufkohlen                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/atmosphaerisches-haerten\/\">\n                        <!--  -->\n                        Atmosph\u00e4risches H\u00e4rten                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/ausscheidungshaerten\/\">\n                        <!-- Ausscheidungsh\u00e4rten -->\n                        Ausscheidungsh\u00e4rten                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/carbonitrieren\/\">\n                        <!--  -->\n                        Carbonitrieren                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/einsatzhaerten\/\">\n                        <!--  -->\n                        Einsatzh\u00e4rten                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/gasnitrieren\/\">\n                        <!--  -->\n                        Gasnitrieren                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/nitrocarburieren\/\">\n                        <!-- Nitrocarburizing  -->\n                        Nitrocarburieren                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/normalisieren\/\">\n                        <!-- Normalisieren -->\n                        Normalisieren                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/spannungsarmgluehen\/\">\n                        <!-- Spannungsarmgl\u00fchen -->\n                        Spannungsarmgl\u00fchen                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/tiefkuehlen\/\">\n                        <!-- Tiefk\u00fchlen -->\n                        Tiefk\u00fchlen                    <\/a>\n                \n                                                        <a class=\"read-more titel\" href=\"https:\/\/www.aalberts-st.com\/de\/verfahren\/weichgluehen\/\">\n                        <!-- Weichgl\u00fchen -->\n                        Weichgl\u00fchen                    <\/a>\n                \n                            \n            \n        <\/div>\n        \n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-775d151a anchor_link  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"775d151a\" data-element_type=\"section\" data-e-type=\"section\" id=\"branchen\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-44284d35\" data-id=\"44284d35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-57e3b57b\" data-id=\"57e3b57b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f68f8ce elementor-widget elementor-widget-heading\" data-id=\"3f68f8ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Branchen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3b6434c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b6434c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1e45948b\" data-id=\"1e45948b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cf64de1 elementor-widget elementor-widget-shortcode\" data-id=\"6cf64de1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">        <div class=\"container industries process\">\n                                                                                <h3 style=\"display: none;\">Werkzeugbau<\/h3>\n                                                        <h3 style=\"display: none;\">Automobilindustrie<\/h3>\n                                                        <h3 style=\"display: none;\">Medizintechnik<\/h3>\n                                                        <div class=\"process-indusries-owl owl-carousel owl-theme\">\n                                            <div class=\"item\">\n                            <article class=\"indsutries process-single red-filter-image\">\n                                                                \n                                <img decoding=\"async\" width=\"1500\" height=\"756\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Tool-Manufacturing.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Headerbild Branche Werkzeugbau - Aalberts surface technologies\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Tool-Manufacturing.jpg 1500w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Tool-Manufacturing-370x186.jpg 370w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Tool-Manufacturing-1024x516.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Tool-Manufacturing-768x387.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Tool-Manufacturing-300x151.jpg 300w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>                                <a class=\"titel\" href=\"https:\/\/www.aalberts-st.com\/de\/branchen\/werkzeugbau\/\">\n                                    <span class=\"h3-fake\">Werkzeugbau<\/span>\n                                <\/a>\n\n                            <\/article>\n                        <\/div>\n                                            <div class=\"item\">\n                            <article class=\"indsutries process-single red-filter-image\">\n                                                                \n                                <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Automobilindustrie\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1.jpg 1920w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1-356x200.jpg 356w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1-1024x576.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1-768x432.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1-1536x864.jpg 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/titel-automotive-quelle-beachten-1920x1080-1-300x169.jpg 300w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>                                <a class=\"titel\" href=\"https:\/\/www.aalberts-st.com\/de\/branchen\/automobilindustrie\/\">\n                                    <span class=\"h3-fake\">Automobilindustrie<\/span>\n                                <\/a>\n\n                            <\/article>\n                        <\/div>\n                                            <div class=\"item\">\n                            <article class=\"indsutries process-single red-filter-image\">\n                                                                \n                                <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-scaled.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Headerbild Branche Medizintechnik - Aalberts surface technologies\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-scaled.jpg 2560w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-300x200.jpg 300w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-1024x683.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-768x512.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-1536x1024.jpg 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Medizintechnik-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                                <a class=\"titel\" href=\"https:\/\/www.aalberts-st.com\/de\/branchen\/medizintechnik\/\">\n                                    <span class=\"h3-fake\">Medizintechnik<\/span>\n                                <\/a>\n\n                            <\/article>\n                        <\/div>\n                                    <\/div>\n            \n            \n\n        <\/div>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a5d57ce anchor_link elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a5d57ce\" data-element_type=\"section\" data-e-type=\"section\" id=\"Kontakt\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3b73d9ec\" data-id=\"3b73d9ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4d1809e7 location-info-detail\" data-id=\"4d1809e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7ffad011 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ffad011\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1d16e0df\" data-id=\"1d16e0df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12a3cea3 elementor-widget elementor-widget-heading\" data-id=\"12a3cea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontakt &amp; Wegbeschreibung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d14551a elementor-widget elementor-widget-text-editor\" data-id=\"3d14551a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aalberts Surface Technologies GmbH<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3213801c elementor-widget elementor-widget-text-editor\" data-id=\"3213801c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLindenmaierstra\u00dfe 19\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-169a003c elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"169a003c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t88471\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b08c5fb elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"2b08c5fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLaupheim\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57e3be61 elementor-widget elementor-widget-text-editor\" data-id=\"57e3be61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGermany\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36c621d6 elementor-widget elementor-widget-shortcode\" data-id=\"36c621d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">        <a href=\"tel:+49 7392 70960\">+49 7392 70960<\/a>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-470db6a2 elementor-widget elementor-widget-shortcode\" data-id=\"470db6a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"all-locations\"><div> <span class=\"latitude\">48.22976<\/span><span class=\"longitude\">9.83458<\/span> <\/div>  <\/div>        <a href=\"mailto:info.laupheim@aalberts-st.com\">info.laupheim@aalberts-st.com<\/a>\n        \n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78489d64 sticky-stopper elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78489d64\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7cfb3c61\" data-id=\"7cfb3c61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>heat treatment \u00dcber den Standort Downloads Unsere Verfahren Branchen Kontakt \u00dcber unseren Standort in Laupheim Der Standort, der aus der fr\u00fcheren H\u00e4rterei des damaligen Drehteilherstellers Lindenmaier hervorging, kann auf eine rund 70-j\u00e4hrige Erfolgsgeschichte zur\u00fcckblicken. Es verf\u00fcgt \u00fcber hochmoderne Verfahrens- und Anagentechnologien, insbesondere in der H\u00e4rterei. Je nach Verfahren, Teilespektrum und Teilebed\u00fcrfnis sorgt der Sondergestellbau f\u00fcr [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[110],"country":[160],"regioe":[174],"certificate":[262,266,269,271,267],"class_list":["post-8501","location","type-location","status-publish","hentry","category-heat-de","country-germany-2","regioe-europe-de","certificate-cqi-9-de","certificate-iatf-16949-de","certificate-iso-14001-de","certificate-iso-50001-de","certificate-iso-9001-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W\u00e4rmebehandlung in Laupheim | Aalberts ST<\/title>\n<meta name=\"description\" content=\"Experte f\u00fcr W\u00e4rmebehandlungen in Laupheim \u2713 zertifizierte W\u00e4rmebehandlungstechnologie \u260e +49 7854 96470 \u25b6 Jetzt kontaktieren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W\u00e4rmebehandlung in Laupheim | Aalberts ST\" \/>\n<meta property=\"og:description\" content=\"Experte f\u00fcr W\u00e4rmebehandlungen in Laupheim \u2713 zertifizierte W\u00e4rmebehandlungstechnologie \u260e +49 7854 96470 \u25b6 Jetzt kontaktieren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/\" \/>\n<meta property=\"og:site_name\" content=\"Aalberts surface technologies\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T13:57:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/\",\"name\":\"W\u00e4rmebehandlung in Laupheim | Aalberts ST\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Werk_Laupheim.jpg\",\"datePublished\":\"2020-12-02T11:28:31+00:00\",\"dateModified\":\"2026-05-06T13:57:55+00:00\",\"description\":\"Experte f\u00fcr W\u00e4rmebehandlungen in Laupheim \u2713 zertifizierte W\u00e4rmebehandlungstechnologie \u260e +49 7854 96470 \u25b6 Jetzt kontaktieren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Werk_Laupheim.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Werk_Laupheim.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/standorte\\\/laupheim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aalberts surface technologies Laupheim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/\",\"name\":\"Aalberts surface technologies\",\"description\":\"mission-critical processes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#organization\",\"name\":\"Aalberts Surface Technologies GmbH\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/group-26.svg\",\"contentUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/group-26.svg\",\"caption\":\"Aalberts Surface Technologies GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W\u00e4rmebehandlung in Laupheim | Aalberts ST","description":"Experte f\u00fcr W\u00e4rmebehandlungen in Laupheim \u2713 zertifizierte W\u00e4rmebehandlungstechnologie \u260e +49 7854 96470 \u25b6 Jetzt kontaktieren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/","og_locale":"de_DE","og_type":"article","og_title":"W\u00e4rmebehandlung in Laupheim | Aalberts ST","og_description":"Experte f\u00fcr W\u00e4rmebehandlungen in Laupheim \u2713 zertifizierte W\u00e4rmebehandlungstechnologie \u260e +49 7854 96470 \u25b6 Jetzt kontaktieren!","og_url":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/","og_site_name":"Aalberts surface technologies","article_modified_time":"2026-05-06T13:57:55+00:00","og_image":[{"url":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/","url":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/","name":"W\u00e4rmebehandlung in Laupheim | Aalberts ST","isPartOf":{"@id":"https:\/\/www.aalberts-st.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/#primaryimage"},"image":{"@id":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg","datePublished":"2020-12-02T11:28:31+00:00","dateModified":"2026-05-06T13:57:55+00:00","description":"Experte f\u00fcr W\u00e4rmebehandlungen in Laupheim \u2713 zertifizierte W\u00e4rmebehandlungstechnologie \u260e +49 7854 96470 \u25b6 Jetzt kontaktieren!","breadcrumb":{"@id":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/#primaryimage","url":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg","contentUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/12\/Werk_Laupheim.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.aalberts-st.com\/de\/standorte\/laupheim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aalberts-st.com\/de\/"},{"@type":"ListItem","position":2,"name":"Aalberts surface technologies Laupheim"}]},{"@type":"WebSite","@id":"https:\/\/www.aalberts-st.com\/de\/#website","url":"https:\/\/www.aalberts-st.com\/de\/","name":"Aalberts surface technologies","description":"mission-critical processes","publisher":{"@id":"https:\/\/www.aalberts-st.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aalberts-st.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.aalberts-st.com\/de\/#organization","name":"Aalberts Surface Technologies GmbH","url":"https:\/\/www.aalberts-st.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.aalberts-st.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/11\/group-26.svg","contentUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/11\/group-26.svg","caption":"Aalberts Surface Technologies GmbH"},"image":{"@id":"https:\/\/www.aalberts-st.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/location\/8501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/location"}],"about":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/types\/location"}],"version-history":[{"count":34,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/location\/8501\/revisions"}],"predecessor-version":[{"id":50322,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/location\/8501\/revisions\/50322"}],"wp:attachment":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/media?parent=8501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/categories?post=8501"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/country?post=8501"},{"taxonomy":"regioe","embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/regioe?post=8501"},{"taxonomy":"certificate","embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/certificate?post=8501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}