{"id":17389,"date":"2021-01-28T08:23:30","date_gmt":"2021-01-28T08:23:30","guid":{"rendered":"https:\/\/aalberts-st.flywheelsites.com\/boric-acid-free-nickel-plating\/"},"modified":"2025-12-22T07:04:51","modified_gmt":"2025-12-22T06:04:51","slug":"borsaeurefreie-nickelabscheidung","status":"publish","type":"post","link":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/","title":{"rendered":"Bors\u00e4urefreie Nickelabscheidung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17389\" class=\"elementor elementor-17389 elementor-15214\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cdd6941 elementor-section-height-min-height page-header elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5cdd6941\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-170a714b\" data-id=\"170a714b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-403bf9cb elementor-widget elementor-widget-heading\" data-id=\"403bf9cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bors\u00e4urefreie Nickelabscheidung<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c114d77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c114d77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c32248e\" data-id=\"3c32248e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cc577a1 elementor-widget elementor-widget-heading\" data-id=\"2cc577a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ein Ersatz von Bors\u00e4ure bringt deutliche Vorteile f\u00fcr die Oberfl\u00e4chenbeschichtung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-157b205e elementor-widget elementor-widget-text-editor\" data-id=\"157b205e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Blei, Cadmium, PFOS, Cr(VI). Mit Arsen und Hydrazin haben wir uns schon lange abgefunden. Die Liste lie\u00dfe sich beliebig lange fortf\u00fchren. Aber Bors\u00e4ure? Dass Bors\u00e4ure unter die Stoffe f\u00e4llt, deren Verwendung aufgrund ihres Gef\u00e4hrdungspotentials verboten werden k\u00f6nnte, f\u00e4llt schwer zu glauben. Nun, Blei ist seit dem Altertum als giftig bekannt und fluorierte oder generell poly-halogenierte Kohlenwasserstoffe wollen wir auch nicht wirklich als Bestandteil unserer Biosph\u00e4re haben. Bors\u00e4ure andererseits ist als Zusatzstoff von Gl\u00e4sern, Pestiziden und Farbanstrichen allgegenw\u00e4rtig und selbst im von Deutschland und Slowenien eingereichten Antrag, Bors\u00e4ure als reproduktionstoxischen SVHC-Stoff (substance of very high concern) zu deklarieren, wird beschrieben, dass epidemiologische Studien am Menschen bislang fehlen bzw. ungen\u00fcgend sind, um nachteilige Effekte auf die Fruchtbarkeit auszuschlie\u00dfen. Im Grunde bedeutet es, dass es bis dato keine Studie gibt, die beweist, dass Bors\u00e4ure f\u00fcr den Menschen reproduktionstoxisch Wirkung hat und damit gef\u00e4hrlich ist.<\/p><p>Nichtsdestotrotz, die j\u00fcngere Vergangenheit hat gezeigt, dass wenn der Gesetzgeber ein Verbot androht, dieses fr\u00fcher oder sp\u00e4ter in Kraft treten wird. Zudem gibt es durchaus auch Beispiele, dass Bors\u00e4ure bei entsprechend hoher Exposition insbesondere bei aquatischen Organismen zu Wachstums- und Fertilit\u00e4tsst\u00f6rungen f\u00fchrt. Daher ist es gerechtfertigt, alternative Systeme zu evaluieren.<\/p><p>Da Bors\u00e4ure gemeinhin in Nickelb\u00e4dern als Puffersubstanz bezeichnet wird und diese Nickelb\u00e4der im Allgemeinen in einem pH-Bereich von 4 bis 4.5 betrieben werden, war es naheliegend, Bors\u00e4ure durch Carbons\u00e4uren zu ersetzen. Deren pKs-Werte (ein Ma\u00df f\u00fcr die St\u00e4rke der S\u00e4ure) liegen meist zwischen 4 und 5 und da die Pufferkapazit\u00e4t eines S\u00e4ure-Base-Paars im Bereich dessen pKs-Wertes am besten ist, waren Carbons\u00e4uren die scheinbar logische Wahl, um den pH-Wert stabil zu halten. Tats\u00e4chlich zeichnen sich solche B\u00e4der durch eine au\u00dferordentlich vorteilhafte pH-Stabilit\u00e4t aus, die weit ausgepr\u00e4gter ist, als bei Verwendung von Bors\u00e4ure. Zudem sind Nickelschichten aus diesen B\u00e4dern weitestgehend porenfrei, was ein Hinweis darauf ist, dass w\u00e4hrend der Abscheidung kein oder praktisch kein festes Nickelhydroxid gebildet wird. Damit ist eine der Hauptanforderungen, die an einen Bors\u00e4ure-Ersatz gestellt werden, erf\u00fcllt. Leider weisen diese Elektrolyte aber einen ganz gewichtigen Nachteil auf: Der von Bors\u00e4ureb\u00e4dern bekannte Glanz und vor allem die Einebnung ist weitgehend verschwunden, sodass diese B\u00e4der f\u00fcr dekorative Anwendungen leider ungeeignet sind. Den Versuchen, diesem Defizit mit h\u00f6heren Glanzmittelkonzentrationen entgegenzuwirken, waren anf\u00e4nglich gewisse Erfolge beschieden, scheiterten fr\u00fcher oder sp\u00e4ter aber im direkten Vergleich mit Bors\u00e4ure-Elektrolyten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be95ae5 elementor-widget elementor-widget-heading\" data-id=\"be95ae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Auf der Suche nach Alternativen zu Bors\u00e4ure<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72b73d5e elementor-widget elementor-widget-text-editor\" data-id=\"72b73d5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Klassische Nickelb\u00e4der bestehen aus einem Gemisch von Nickelsulfat und Nickelchlorid, Bors\u00e4ure, Netzmittel, sogenannten Grundgl\u00e4nzern, wie zum Beispiel Natrium-Saccharin, sowie einebnenden Substanzen, die im Allgemeinen eine Alkingruppe als Funktionalit\u00e4t aufweisen. Nun geh\u00f6rt es zum kleinen Einmaleins des Koordinationschemikers, dass nicht nur Pufferkapazit\u00e4ten im Bereich des pKs-Wertes am h\u00f6chsten sind, sondern auch Komplexstabilit\u00e4ten zwischen Komplexbildnern und Metallionen. Und hier besteht ein entscheidender Unterschied zwischen Nickel und Bors\u00e4ure einerseits und Nickel und Carbons\u00e4uren andererseits. Im Arbeitsbereich eines Nickelbades findet eine ausgepr\u00e4gte Komplexbildung zwischen Nickel und Carbons\u00e4uren statt, w\u00e4hrend dies mit Bors\u00e4ure aufgrund des h\u00f6heren pKs-Wertes erst bei h\u00f6heren pH-Werten stattfindet. Zwar ist durchaus bekannt, dass je nach Medium, Reaktionspartner, Konzentration und Temperatur Bors\u00e4ure pKs-Werte annehmen kann, die mit Carbons\u00e4uren vergleichbar sind, allerdings beg\u00fcnstigen die Betriebsparameter von Nickelb\u00e4dern eher h\u00f6here pKs-Werte, die die starke Komplexbildung bei pH 4 bis 4.5 zwischen Nickel und Bors\u00e4ure unwahrscheinlich machen.<\/p><p>Es scheint daher nicht so wichtig zu sein, welche Wirkung Bors\u00e4ure hat bzw. was sie tut, sondern viel mehr, was sie eben nicht tut, n\u00e4mlich Ni2+ koordinativ zu s\u00e4ttigen und damit f\u00fcr einebnende Substanzen unzug\u00e4nglich zu machen.<\/p><p>Zusammengefasst muss ein Bors\u00e4ure-Ersatz zwei Bedingungen erf\u00fcllen: einerseits eine m\u00f6glichst geringe Neigung Nickel im Bereich des Arbeits-pH-Wertes zu binden, was im Gegenzug eine direkte Bindung zwischen Einebner und Nickel erlaubt, aber andererseits \u2013 beim und leicht unterhalb des pH-Wertes, bei welchem Nickel-Hydrolyse einsetzt \u2013 Nickel sehr stark zu binden, um so die Bildung von Nickelhydroxid zu verhindern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ae3c9e elementor-widget elementor-widget-heading\" data-id=\"0ae3c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die L\u00f6sung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cba6346 elementor-widget elementor-widget-text-editor\" data-id=\"4cba6346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die\u00a0<a href=\"https:\/\/www.riag.ch\">riag Oberfl\u00e4chentechnik AG<\/a>\u00a0hat eine ganze Verbindungsklasse identifiziert, welche die oben genannten Bedingungen geradezu perfekt vereint. Die daraus abgeleiteten Produkte sind nun im Begriff nach einer erfolgreich abgeschlossenen Testphase bors\u00e4urehaltige Verfahren schrittweise zu ersetzen. Besonders hervorzuheben sind folgende Merkmale:<\/p><ol><li>Erweiterung des Arbeitsfensters: Die neue Verbindungsklasse erlaubt ein Beschichten bei h\u00f6heren pH-Werten. Damit kann neu zwischen pH 3.8 bis in Extremf\u00e4llen pH 5.5 beschichtet werden, ohne dass dabei Abtrennungen im hohen Stromdichtebereich beobachtet werden.<\/li><li>Verbesserung der Duktilit\u00e4t: Die effiziente Unterdr\u00fcckung der Nickelhydroxid-Bildung verhindert weitgehend eine Verspr\u00f6dung der Nickelschicht.<\/li><li>Reduzierter Additiv-Verbrauch: Da der Abbau von Additiven unter anderem vom pH-Wert abh\u00e4ngig ist, steht es dem Beschichtet offen, die Beschichtungsparameter so anzupassen, dass bei gleichbleibenden dekorativen Eigenschaften ein signifikant reduzierter Additiv-Verbrauch resultiert.<\/li><li>Verbesserte Schichtdickenverteilung: Die f\u00fcr den\u00a0<a href=\"https:\/\/aalberts-st.com\/de\/standorte\/\">Oberfl\u00e4chenbeschichter<\/a>\u00a0wahrscheinlich interessanteste Eigenschaft ist die gleichm\u00e4\u00dfigere Schichtdickenverteilung, welche deutlich k\u00fcrzere Beschichtungszeiten erlaubt.<\/li><li>Vollst\u00e4ndige Kompatibilit\u00e4t der neuen Verbindungen mit Bors\u00e4ure: Damit wird ein nahtloser \u00dcbergang von Bors\u00e4ure zu den neuen Verfahren gew\u00e4hrleistet, ohne dass dabei Produktionsunterbrechungen bef\u00fcrchtet werden m\u00fcssen.<\/li><\/ol><p>Abschlie\u00dfend kann festgehalten werden, dass was anf\u00e4nglich als staatlich verordnete Zw\u00e4ngerei wahrgenommen wurde, sich als Gl\u00fccksfall f\u00fcr die Technik erweist. W\u00e4hrend das Blei- und Chrom(VI)-Verbot mit erheblichen Qualit\u00e4tseinbu\u00dfen beim Endprodukt einhergeht, scheint bei der Bors\u00e4ure-Substitution das Gegenteil der Fall zu sein.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-43a38aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43a38aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a4f8257\" data-id=\"4a4f8257\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b5df47f elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"4b5df47f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Noch Fragen?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c0b3abc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2c0b3abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>managing director<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7772fb0b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7772fb0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cfffa41 elementor-widget elementor-widget-text-editor\" data-id=\"3cfffa41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Manfred Beck<br \/><\/strong>managing director<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c9e1fff elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"6c9e1fff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:manfred.beck@riag.ch\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-Mail schreiben<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-534b67d3 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"534b67d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/company\/aalberts-surface-treatment-gmbh\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fdb78d2\" data-id=\"6fdb78d2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-342ac33a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"342ac33a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1ff73789\" data-id=\"1ff73789\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d59a51b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1d59a51b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/company\/aalberts-surface-treatment-gmbh\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin-in\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Folgen Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c8c5386 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1c8c5386\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-648b36c3 elementor-widget elementor-widget-heading\" data-id=\"648b36c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Auch relevant<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45c7cfc6 elementor-widget__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"45c7cfc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79e58bcb elementor-widget elementor-widget-wpgb-grid\" data-id=\"79e58bcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpgb-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Gridbuilder \u1d42\u1d3e Plugin (https:\/\/wpgridbuilder.com) -->\n<div class=\"wp-grid-builder wpgb-grid-11\" data-options=\"{&quot;id&quot;:11,&quot;type&quot;:&quot;masonry&quot;,&quot;source&quot;:&quot;post_type&quot;,&quot;loader&quot;:0,&quot;layout&quot;:&quot;vertical&quot;,&quot;reveal&quot;:0,&quot;isMainQuery&quot;:false,&quot;lazyLoad&quot;:0,&quot;cardSizes&quot;:{&quot;9999&quot;:{&quot;columns&quot;:1,&quot;height&quot;:240,&quot;gutter&quot;:0,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;1200&quot;:{&quot;columns&quot;:1,&quot;height&quot;:240,&quot;gutter&quot;:0,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;992&quot;:{&quot;columns&quot;:1,&quot;height&quot;:220,&quot;gutter&quot;:0,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;768&quot;:{&quot;columns&quot;:1,&quot;height&quot;:220,&quot;gutter&quot;:0,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;576&quot;:{&quot;columns&quot;:1,&quot;height&quot;:200,&quot;gutter&quot;:0,&quot;ratio&quot;:&quot;1.33333&quot;},&quot;320&quot;:{&quot;columns&quot;:1,&quot;height&quot;:200,&quot;gutter&quot;:30,&quot;ratio&quot;:&quot;1.33333&quot;}},&quot;fitRows&quot;:0,&quot;equalRows&quot;:0,&quot;equalColumns&quot;:0,&quot;fillLastRow&quot;:0,&quot;centerLastRow&quot;:0,&quot;horizontalOrder&quot;:0,&quot;fullWidth&quot;:0,&quot;transitionDelay&quot;:100,&quot;gallerySlideshow&quot;:0,&quot;rowsNumber&quot;:1,&quot;slideAlign&quot;:&quot;left&quot;,&quot;groupCells&quot;:1,&quot;draggable&quot;:1,&quot;initialIndex&quot;:0,&quot;contain&quot;:0,&quot;freeScroll&quot;:0,&quot;freeFriction&quot;:&quot;0.075&quot;,&quot;friction&quot;:&quot;0.285&quot;,&quot;attraction&quot;:&quot;0.025&quot;,&quot;autoPlay&quot;:0,&quot;pageDotAriaLabel&quot;:&quot;Page dot %d&quot;,&quot;isPreview&quot;:false,&quot;isGutenberg&quot;:false,&quot;rightToLeft&quot;:false}\"><div class=\"wpgb-svg-icons\" hidden>\n\t<svg viewBox=\"0 0 120 24\" width=\"0\" height=\"0\">\n\t<defs>\n        <polygon id=\"wpgb-star-svg\" points=\"12 2.5 15.1 8.8 22 9.8 17 14.6 18.2 21.5 12 18.3 5.8 21.5 7 14.6 2 9.8 8.9 8.8\"><\/polygon>\n    <\/defs>\n    <symbol id=\"wpgb-rating-stars-svg\">\n        <use xlink:href=\"#wpgb-star-svg\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"24\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"48\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"72\"><\/use>\n        <use xlink:href=\"#wpgb-star-svg\" x=\"96\"><\/use>\n    <\/symbol>\n<\/svg>\n<\/div>\n<div class=\"wpgb-wrapper\">\n\t<div class=\"wpgb-main\">\n\t<div class=\"wpgb-layout\">\n\t<div class=\"wpgb-viewport\">\n\t\t<div class=\"wpgb-masonry\">\n\t\t\t                            <article class=\"wpgb-card wpgb-card-8 wpgb-post-45081\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\" data-action><h3 class=\"wpgb-block-2\">EcoVadis Bronze-Medaille Auszeichnung<\/h3><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/ecovadis-auszeichnung\/\"><\/a><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/ecovadis-auszeichnung\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-8 wpgb-post-44664\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\" data-action><h3 class=\"wpgb-block-2\">PFAS-freie Versiegelung (hart-)anodischer Schichten<\/h3><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/pfas-freie-versiegelung-hart-coat-sil\/\"><\/a><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/pfas-freie-versiegelung-hart-coat-sil\/\"><\/a><\/div><\/div><\/article><article class=\"wpgb-card wpgb-card-8 wpgb-post-38535\" data-col=\"1\" data-row=\"1\" data-format=\"standard\"><div class=\"wpgb-card-wrapper\"><div class=\"wpgb-card-inner\" data-action><div class=\"wpgb-card-media wpgb-scheme-light\"><\/div><div class=\"wpgb-card-content wpgb-scheme-dark\"><div class=\"wpgb-card-body\" data-action><h3 class=\"wpgb-block-2\">Alternative zum Chrom(VI)-haltigen Elektrolyten bei SELGA-COAT\u00ae<\/h3><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/nachhaltig-effizient-alternative-elektrolyt-selektive-anodisation\/\"><\/a><\/div><\/div><a class=\"wpgb-card-layer-link\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/nachhaltig-effizient-alternative-elektrolyt-selektive-anodisation\/\"><\/a><\/div><\/div><\/article>\t\t<\/div>\n\t<\/div>\n\t<\/div>\n\t<\/div>\n\t\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-566594ef elementor-widget elementor-widget-shortcode\" data-id=\"566594ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class='container_detail__post'><div class=\"recent-most_viewed--nav\"> <span data-id=\"1\" class=\"active\">Am meisten gelesen\n<\/span> <span  data-id=\"2\">Neueste<\/span><\/div><div class=\"tab-trigger most_viewed_posts active\" data-id=\"1\"><a href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/corona-virus-wir-sind-lieferfaehig\/\"><img decoding=\"async\" width=\"370\" height=\"135\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/Coronavirus-scaled-new-370x135.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Coronavirus news\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/Coronavirus-scaled-new-370x135.jpg 370w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/Coronavirus-scaled-new-300x109.jpg 300w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/Coronavirus-scaled-new.jpg 687w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/><span>Corona-Virus: Wir sind lieferf\u00e4hig!<\/span><\/a><a href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/case-study-pfas-freie-lebensdauerschmierung\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"case-study-press-jaw\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-300x200.jpg 300w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-1024x683.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-768x512.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-1536x1024.jpg 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><span>Case study: PFAS-freie Lebensdauerschmierung f\u00fcr Rohrpresszangen<\/span><\/a><a href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/neue-halle-tatabanya\/\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Tatabanya Opening\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-300x200.jpg 300w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-1024x683.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-768x512.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-1536x1024.jpg 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-2048x1366.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><span>Aalberts surface technologies in Tatab\u00e1nya expandiert &#8211; neue 12.000 m\u00b2 gro\u00dfe Halle<\/span><\/a><\/div><div class=\"tab-trigger recent_posts\" data-id=\"2\"><a href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/case-study-pfas-freie-lebensdauerschmierung\/\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"case-study-press-jaw\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-300x200.jpg 300w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-1024x683.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-768x512.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-1536x1024.jpg 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2026\/06\/case-study-press-jaw-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><span>Case study: PFAS-freie Lebensdauerschmierung f\u00fcr Rohrpresszangen<\/span><\/a><a href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/neue-halle-tatabanya\/\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Tatabanya Opening\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-300x200.jpg 300w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-1024x683.jpg 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-768x512.jpg 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-1536x1024.jpg 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/11\/Tatabanya-Opening-2048x1366.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><span>Aalberts surface technologies in Tatab\u00e1nya expandiert &#8211; neue 12.000 m\u00b2 gro\u00dfe Halle<\/span><\/a><a href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/uebernahme-paulo-products-company\/\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"123\" src=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2021-08-17-at-11.54.30-AM-e1629219575409-370x123.webp\" class=\"attachment-medium size-medium wp-post-image\" alt=\"acquisition of Paulo Products Company (Paulo)\" srcset=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2021-08-17-at-11.54.30-AM-e1629219575409-370x123.webp 370w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2021-08-17-at-11.54.30-AM-e1629219575409-1024x340.webp 1024w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2021-08-17-at-11.54.30-AM-e1629219575409-768x255.webp 768w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2021-08-17-at-11.54.30-AM-e1629219575409-1536x511.webp 1536w, https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2025\/01\/Screen-Shot-2021-08-17-at-11.54.30-AM-e1629219575409.webp 2000w\" sizes=\"(max-width: 370px) 100vw, 370px\" \/><span>\u00dcbernahme der Paulo Products Company (Paulo)<\/span><\/a><\/div><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ein Ersatz von Bors\u00e4ure bringt deutliche Vorteile f\u00fcr die Oberfl\u00e4chenbeschichtung Blei, Cadmium, PFOS, Cr(VI). Mit Arsen und Hydrazin haben wir uns schon lange abgefunden. Die Liste lie\u00dfe sich beliebig lange fortf\u00fchren. Aber Bors\u00e4ure? Dass Bors\u00e4ure unter die Stoffe f\u00e4llt, deren Verwendung aufgrund ihres Gef\u00e4hrdungspotentials verboten werden k\u00f6nnte, f\u00e4llt schwer zu glauben. Nun, Blei ist seit [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80],"tags":[],"class_list":["post-17389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bors\u00e4urefreie Nickelabscheidung | Nickelschichten | Aalberts ST<\/title>\n<meta name=\"description\" content=\"Eine neue Verbindungsklasse sorgt f\u00fcr den von galvanischen Nickelschichten Glanz, ohne den Einsatz von Bors\u00e4ure \u25b6 Hier mehr erfahren!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bors\u00e4urefreie Nickelabscheidung | Nickelschichten | Aalberts ST\" \/>\n<meta property=\"og:description\" content=\"Eine neue Verbindungsklasse sorgt f\u00fcr den von galvanischen Nickelschichten Glanz, ohne den Einsatz von Bors\u00e4ure \u25b6 Hier mehr erfahren!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/\" \/>\n<meta property=\"og:site_name\" content=\"Aalberts surface technologies\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-28T08:23:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T06:04:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/dnc-weiterstadt-1920-700-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marius Weber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marius Weber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/\"},\"author\":{\"name\":\"Marius Weber\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#\\\/schema\\\/person\\\/91e71c5a3744ad2b7177c4bf4e490a84\"},\"headline\":\"Bors\u00e4urefreie Nickelabscheidung\",\"datePublished\":\"2021-01-28T08:23:30+00:00\",\"dateModified\":\"2025-12-22T06:04:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/\"},\"wordCount\":980,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/dnc-weiterstadt-1920-700-scaled.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/\",\"name\":\"Bors\u00e4urefreie Nickelabscheidung | Nickelschichten | Aalberts ST\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/dnc-weiterstadt-1920-700-scaled.jpg\",\"datePublished\":\"2021-01-28T08:23:30+00:00\",\"dateModified\":\"2025-12-22T06:04:51+00:00\",\"description\":\"Eine neue Verbindungsklasse sorgt f\u00fcr den von galvanischen Nickelschichten Glanz, ohne den Einsatz von Bors\u00e4ure \u25b6 Hier mehr erfahren!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/dnc-weiterstadt-1920-700-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/dnc-weiterstadt-1920-700-scaled.jpg\",\"width\":2560,\"height\":933,\"caption\":\"Weiterstadt, 16.11.2012, Einweihung der neuen Betriebsst\u00c3\u00a4tte des Oberfl\u00c3\u00a4chenveredlers AHC Chemisch Nickel , mit dem Werksleiter Uwe Beiswenger (Glatze) und dem Gesch\u00c3\u00a4ftsf\u00c3\u00bchrer Hartmut Sauer (Kinnbart), vernickelten Maschinenbauteilen, der Produktionshalle m, dem Chemiebad, sowie den Mitarbeitern in der Produktion Sigrid Mengner und Fair Eken die vernickelte Bohrer sortieren, Foto: Vollformat\\\/ Alexander Heimann, Sch\u00c3\u00a4fergasse 5, 65428 R\u00c2\u0178\u00c3\u00bcsselsheim, Fon 0177-5626350, Bankverbindung Kreissparkasse Gross Gerau BLZ. 50852553 , KTO. 16003352. Alle Honorare zzgl. 7% MwSt.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/ueber-uns\\\/news\\\/borsaeurefreie-nickelabscheidung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bors\u00e4urefreie Nickelabscheidung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/\",\"name\":\"Aalberts surface technologies\",\"description\":\"mission-critical processes\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#organization\",\"name\":\"Aalberts Surface Technologies GmbH\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/group-26.svg\",\"contentUrl\":\"https:\\\/\\\/www.aalberts-st.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/group-26.svg\",\"caption\":\"Aalberts Surface Technologies GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aalberts-st.com\\\/de\\\/#\\\/schema\\\/person\\\/91e71c5a3744ad2b7177c4bf4e490a84\",\"name\":\"Marius Weber\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bors\u00e4urefreie Nickelabscheidung | Nickelschichten | Aalberts ST","description":"Eine neue Verbindungsklasse sorgt f\u00fcr den von galvanischen Nickelschichten Glanz, ohne den Einsatz von Bors\u00e4ure \u25b6 Hier mehr erfahren!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/","og_locale":"de_DE","og_type":"article","og_title":"Bors\u00e4urefreie Nickelabscheidung | Nickelschichten | Aalberts ST","og_description":"Eine neue Verbindungsklasse sorgt f\u00fcr den von galvanischen Nickelschichten Glanz, ohne den Einsatz von Bors\u00e4ure \u25b6 Hier mehr erfahren!","og_url":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/","og_site_name":"Aalberts surface technologies","article_published_time":"2021-01-28T08:23:30+00:00","article_modified_time":"2025-12-22T06:04:51+00:00","og_image":[{"width":2560,"height":933,"url":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/dnc-weiterstadt-1920-700-scaled.jpg","type":"image\/jpeg"}],"author":"Marius Weber","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Marius Weber","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#article","isPartOf":{"@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/"},"author":{"name":"Marius Weber","@id":"https:\/\/www.aalberts-st.com\/de\/#\/schema\/person\/91e71c5a3744ad2b7177c4bf4e490a84"},"headline":"Bors\u00e4urefreie Nickelabscheidung","datePublished":"2021-01-28T08:23:30+00:00","dateModified":"2025-12-22T06:04:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/"},"wordCount":980,"publisher":{"@id":"https:\/\/www.aalberts-st.com\/de\/#organization"},"image":{"@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/dnc-weiterstadt-1920-700-scaled.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/","url":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/","name":"Bors\u00e4urefreie Nickelabscheidung | Nickelschichten | Aalberts ST","isPartOf":{"@id":"https:\/\/www.aalberts-st.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#primaryimage"},"image":{"@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/dnc-weiterstadt-1920-700-scaled.jpg","datePublished":"2021-01-28T08:23:30+00:00","dateModified":"2025-12-22T06:04:51+00:00","description":"Eine neue Verbindungsklasse sorgt f\u00fcr den von galvanischen Nickelschichten Glanz, ohne den Einsatz von Bors\u00e4ure \u25b6 Hier mehr erfahren!","breadcrumb":{"@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#primaryimage","url":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/dnc-weiterstadt-1920-700-scaled.jpg","contentUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2021\/01\/dnc-weiterstadt-1920-700-scaled.jpg","width":2560,"height":933,"caption":"Weiterstadt, 16.11.2012, Einweihung der neuen Betriebsst\u00c3\u00a4tte des Oberfl\u00c3\u00a4chenveredlers AHC Chemisch Nickel , mit dem Werksleiter Uwe Beiswenger (Glatze) und dem Gesch\u00c3\u00a4ftsf\u00c3\u00bchrer Hartmut Sauer (Kinnbart), vernickelten Maschinenbauteilen, der Produktionshalle m, dem Chemiebad, sowie den Mitarbeitern in der Produktion Sigrid Mengner und Fair Eken die vernickelte Bohrer sortieren, Foto: Vollformat\/ Alexander Heimann, Sch\u00c3\u00a4fergasse 5, 65428 R\u00c2\u0178\u00c3\u00bcsselsheim, Fon 0177-5626350, Bankverbindung Kreissparkasse Gross Gerau BLZ. 50852553 , KTO. 16003352. Alle Honorare zzgl. 7% MwSt."},{"@type":"BreadcrumbList","@id":"https:\/\/www.aalberts-st.com\/de\/ueber-uns\/news\/borsaeurefreie-nickelabscheidung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aalberts-st.com\/de\/"},{"@type":"ListItem","position":2,"name":"Bors\u00e4urefreie Nickelabscheidung"}]},{"@type":"WebSite","@id":"https:\/\/www.aalberts-st.com\/de\/#website","url":"https:\/\/www.aalberts-st.com\/de\/","name":"Aalberts surface technologies","description":"mission-critical processes","publisher":{"@id":"https:\/\/www.aalberts-st.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aalberts-st.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.aalberts-st.com\/de\/#organization","name":"Aalberts Surface Technologies GmbH","url":"https:\/\/www.aalberts-st.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.aalberts-st.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/11\/group-26.svg","contentUrl":"https:\/\/www.aalberts-st.com\/wp-content\/uploads\/2020\/11\/group-26.svg","caption":"Aalberts Surface Technologies GmbH"},"image":{"@id":"https:\/\/www.aalberts-st.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.aalberts-st.com\/de\/#\/schema\/person\/91e71c5a3744ad2b7177c4bf4e490a84","name":"Marius Weber"}]}},"_links":{"self":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/posts\/17389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/comments?post=17389"}],"version-history":[{"count":20,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/posts\/17389\/revisions"}],"predecessor-version":[{"id":49112,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/posts\/17389\/revisions\/49112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/media\/18208"}],"wp:attachment":[{"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/media?parent=17389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/categories?post=17389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aalberts-st.com\/de\/wp-json\/wp\/v2\/tags?post=17389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}